{"id":6427,"date":"2021-05-18T14:23:29","date_gmt":"2021-05-18T14:23:29","guid":{"rendered":"https:\/\/museudoporto.pt\/operative-programmes\/"},"modified":"2021-05-18T14:23:29","modified_gmt":"2021-05-18T14:23:29","slug":"operative-programmes","status":"publish","type":"page","link":"https:\/\/museudoporto.pt\/en\/operative-programmes\/","title":{"rendered":"Operative Programmes"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":18,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-operative-programs.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-6427","page","type-page","status-publish","hentry"],"acf":{"breadcrumb":[{"page":"Do"}],"intro_text":"<p>! Given the current pandemic context, operative programmes have been suspend. Some activities were carried out with small groups that inhabit the geographical areas of the stations or were transferred to the <a href=\"https:\/\/museudoporto.pt\/gabinete-atmosferico\/\">Atmospheric Cabinet<\/a>.<\/p>\n<p>6 Programs orchestrate the City Museum, composing the articulations designed between its 17 Stations and 5 Axes.<\/p>\n","ambient_sound":false,"operative_programs":[{"ID":6967,"post_author":"11","post_date":"2021-06-01 13:22:29","post_date_gmt":"2021-06-01 13:22:29","post_content":"","post_title":"Oficina","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"oficinas","to_ping":"","pinged":"","post_modified":"2023-02-20 12:20:06","post_modified_gmt":"2023-02-20 12:20:06","post_content_filtered":"","post_parent":0,"guid":"https:\/\/museudoporto.pt\/?post_type=operative_program&#038;p=6967","menu_order":0,"post_type":"operative_program","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":539,"post_author":"18","post_date":"2020-10-20 11:13:52","post_date_gmt":"2020-10-20 11:13:52","post_content":"","post_title":"Deriva","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"deriva","to_ping":"","pinged":"","post_modified":"2023-01-20 16:07:55","post_modified_gmt":"2023-01-20 16:07:55","post_content_filtered":"","post_parent":0,"guid":"https:\/\/museudoporto.pt\/?post_type=operative_program&#038;p=539","menu_order":0,"post_type":"operative_program","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":9413,"post_author":"7","post_date":"2022-03-29 13:42:08","post_date_gmt":"2022-03-29 13:42:08","post_content":"","post_title":"Caminhos","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"caminhos","to_ping":"","pinged":"","post_modified":"2024-11-19 15:58:06","post_modified_gmt":"2024-11-19 15:58:06","post_content_filtered":"","post_parent":0,"guid":"https:\/\/museudoporto.pt\/?post_type=operative_program&#038;p=9413","menu_order":0,"post_type":"operative_program","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":582,"post_author":"18","post_date":"2020-10-20 18:54:00","post_date_gmt":"2020-10-20 18:54:00","post_content":"","post_title":"Sonda","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"sonda","to_ping":"","pinged":"","post_modified":"2023-02-02 16:39:27","post_modified_gmt":"2023-02-02 16:39:27","post_content_filtered":"","post_parent":0,"guid":"https:\/\/museudoporto.pt\/?post_type=operative_program&#038;p=582","menu_order":0,"post_type":"operative_program","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":584,"post_author":"18","post_date":"2020-10-20 19:00:55","post_date_gmt":"2020-10-20 19:00:55","post_content":"","post_title":"Invent\u00e1rio","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"inventario","to_ping":"","pinged":"","post_modified":"2023-01-17 10:17:38","post_modified_gmt":"2023-01-17 10:17:38","post_content_filtered":"","post_parent":0,"guid":"https:\/\/museudoporto.pt\/?post_type=operative_program&#038;p=584","menu_order":0,"post_type":"operative_program","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":583,"post_author":"18","post_date":"2020-10-20 18:58:12","post_date_gmt":"2020-10-20 18:58:12","post_content":"","post_title":"Resgate","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"resgate","to_ping":"","pinged":"","post_modified":"2024-12-12 10:20:16","post_modified_gmt":"2024-12-12 10:20:16","post_content_filtered":"","post_parent":0,"guid":"https:\/\/museudoporto.pt\/?post_type=operative_program&#038;p=583","menu_order":0,"post_type":"operative_program","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":9274,"post_author":"11","post_date":"2022-02-28 12:41:38","post_date_gmt":"2022-02-28 12:41:38","post_content":"","post_title":"Dia do Vizinho","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"dia-do-vizinho","to_ping":"","pinged":"","post_modified":"2024-12-12 10:04:03","post_modified_gmt":"2024-12-12 10:04:03","post_content_filtered":"","post_parent":0,"guid":"https:\/\/museudoporto.pt\/?post_type=operative_program&#038;p=9274","menu_order":0,"post_type":"operative_program","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":528,"post_author":"18","post_date":"2020-10-16 15:26:49","post_date_gmt":"2020-10-16 15:26:49","post_content":"","post_title":"Escuta","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"escuta","to_ping":"","pinged":"","post_modified":"2022-04-04 14:33:02","post_modified_gmt":"2022-04-04 14:33:02","post_content_filtered":"","post_parent":0,"guid":"https:\/\/museudoporto.pt\/?post_type=operative_program&#038;p=528","menu_order":0,"post_type":"operative_program","post_mime_type":"","comment_count":"0","filter":"raw"}]},"_links":{"self":[{"href":"https:\/\/museudoporto.pt\/en\/wp-json\/wp\/v2\/pages\/6427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museudoporto.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/museudoporto.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/museudoporto.pt\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/museudoporto.pt\/en\/wp-json\/wp\/v2\/comments?post=6427"}],"version-history":[{"count":1,"href":"https:\/\/museudoporto.pt\/en\/wp-json\/wp\/v2\/pages\/6427\/revisions"}],"predecessor-version":[{"id":6428,"href":"https:\/\/museudoporto.pt\/en\/wp-json\/wp\/v2\/pages\/6427\/revisions\/6428"}],"wp:attachment":[{"href":"https:\/\/museudoporto.pt\/en\/wp-json\/wp\/v2\/media?parent=6427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}